{"id":1467,"date":"2017-08-30T22:24:41","date_gmt":"2017-08-30T16:24:41","guid":{"rendered":"https:\/\/mayanruins.travel\/?post_type=product&#038;p=1467"},"modified":"2024-07-03T06:23:00","modified_gmt":"2024-07-03T00:23:00","slug":"show-de-noche-en-chichen-itza","status":"publish","type":"product","link":"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/","title":{"rendered":"Show de Noche en Chichen Itz\u00e1"},"content":{"rendered":"<p>[vc_row][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h2>\u00a1Descubre todo acerca de los mayas con el Tour Show de Noche en Chichen Itz\u00e1!<\/h2>\n<p>Ser\u00e1 un d\u00eda en donde podr\u00e1s llenarte de energ\u00eda en la antigua Chichen Itz\u00e1, podr\u00e1s conocer una de las nuevas siete maravillas del mundo, el campo de Juego de pelota, una aldea maya, sumergirte en las aguas cristalinas de un cenote, disfrutar de la arquitectura de Valladolid y deleitarte con autentica comida yucateca. Adem\u00e1s de disfrutar de un espectacular\u00a0 Show de Noche en Chichen Itz\u00e1, que pondr\u00e1 tus sentidos a flor de piel.<\/p>\n<h3>\u00a1Marav\u00edllate con el Show de Noche en Chichen Itz\u00e1!<\/h3>\n<p>\u00bfTe imaginas tener como escenario la Pir\u00e1mide de Kukulk\u00e1n en un espect\u00e1culo de luz y sonido?<\/p>\n<p>El Show de Noche en Chichen Itz\u00e1 es una oportunidad para disfrutar de la luz de la luna, un cielo lleno de estrellas,\u00a0 incre\u00edble m\u00fasica, efectos especiales de luz y todo el misticismo de est\u00e1 incre\u00edble ciudad maya.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;1647&#8243; img_size=&#8221;full&#8221; alignment=&#8221;right&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]A tu llegada a las ruinas arqueol\u00f3gicas comenzar\u00e1s a disfrutar del Show de Noche en Chichen Itz\u00e1. El espect\u00e1culo comienza con un recorrido por las ruinas arqueol\u00f3gicas que se encuentran alrededor de la explanada de Chichen Itz\u00e1.<\/p>\n<p>Despu\u00e9s del recorrido inicial que dura aproximadamente 45 minutos en donde la magia de la noche y el misterio de las ruinas te har\u00e1n vivir toda una experiencia, podr\u00e1s acomodarte para regocijarte con la protagonista de la noche: la pir\u00e1mide del dios Kukulk\u00e1n.<\/p>\n<h2>\u00a1Conoce m\u00e1s de la cultura maya\u00a0 con el Show de Noche en Chichen Itz\u00e1!<\/h2>\n<p>Una proyecci\u00f3n narrativa llena de magia que coordinada con m\u00fasica ser\u00e1 la encargada de brindarte la experiencia m\u00e1s enriquecedora de noche en Chichen Itz\u00e1.<\/p>\n<p>En total son 25 minutos de historia maya representada de la mejor manera, prepara tus sentidos para que disfrutes al cien por ciento las proyecciones en 3D\u00a0 sobre la pir\u00e1mide de Kukulk\u00e1n con el mejor show de luces y audio que puedas imaginar.<\/p>\n<p>Este maravilloso espect\u00e1culo de luz y sonido que te pondr\u00e1 la piel de gallina, es una representaci\u00f3n con luces multicolores te llevar\u00e1 a los d\u00edas de equinoccio, ah\u00ed ver\u00e1s el movimiento de la serpiente emplumada y vivir\u00e1s fascinantes momentos de la vida maya.<\/p>\n<p>Sin duda conocer\u00e1s desde otra perspectiva el mundo maya \u00a1Ser\u00e1 una noche inolvidable![\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"slz-shortcode block-title-10420014086a581ad4b6143 \">\r\n<h3 class=\"slz-shortcode title-style-3\">\u00bfQu\u00e9 incluye el tour?<\/h3><\/div>\r\n<div class=\"slz-shortcode item-list-style06 item-list-17276374316a581ad4b627a wrapper-journey \" data-item=5><div class=\"item feature-item\"><i class=\"icon-journey fa fa-car\"><\/i><div class=\"text\">Transportaci\u00f3n de\/hasta tu hotel<\/div><\/div><div class=\"item feature-item\"><i class=\"icon-journey flaticon-food-1\"><\/i><div class=\"text\">Snacks<\/div><\/div><div class=\"item feature-item\"><i class=\"icon-journey flaticon-cup\"><\/i><div class=\"text\">Bebidas no alcoh\u00f3licas abordo<\/div><\/div><div class=\"item feature-item\"><i class=\"icon-journey flaticon-food-2\"><\/i><div class=\"text\">Cena Buffet de comida yucateca.<\/div><\/div><div class=\"item feature-item\"><i class=\"icon-journey flaticon-man\"><\/i><div class=\"text\">Gu\u00eda biling\u00fce<\/div><\/div><\/div>[vc_empty_space][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1466409302371{padding-top: 60px !important;}&#8221;][vc_column]<div class=\"slz-shortcode tour-schedule overview-block clearfix \">\r\n\t\t<h3 class=\"title-style-3\">Itinerario<\/h3>\r\n\t\r\n\t<div class=\"timeline-container\">\r\n\t\t<div class=\"timeline\">\r\n\t\t\t\t\t\t<div class=\"timeline-block timeline-1\">\r\n\t\t\t\t<div class=\"timeline-title\">\r\n\t\t\t\t\t<span>9:00 am<\/span>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"timeline-content medium-margin-top\">\r\n\t\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t\t<div class=\"timeline-point\"><i class=\"fa fa-circle-o\"><\/i><\/div>\r\n\t\t\t\t\t\t<div class=\"timeline-custom-col content-col \">\r\n\t\t\t\t\t\t\t<div class=\"timeline-location-block\">\r\n\t\t\t\t\t\t\t\t<p class=\"location-name\">\r\n\t\t\t\t\t\t\t\t\tPick up\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-map-marker icon-marker\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t\t<div class=\"description\">\r\n\t\t\t\t\t\t\t\t\tEsta valiosa experiencia comenzar\u00e1 alrededor en de las 9:00 am, un c\u00f3modo transporte en donde una deliciosa barra de snaks y bebidas no alcoh\u00f3licas te dar\u00e1n energ\u00eda para vivir una incre\u00edble experiencia. \t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"timeline-custom-col image-col\" data-slick=\"{&quot;slidesToShow&quot;:1,&quot;slidesToScroll&quot;:1,&quot;dots&quot;:true,&quot;arrows&quot;:true,&quot;autoplay&quot;:true,&quot;infinite&quot;:true,&quot;speed&quot;:300,&quot;fade&quot;:false}\"><div class=\"timeline-image-block items\"><img decoding=\"async\" src=\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/ek-balam-mayan-ruins-pick-up.jpg\" alt=\"\"><\/div><\/div>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"timeline-block timeline-2\">\r\n\t\t\t\t<div class=\"timeline-title\">\r\n\t\t\t\t\t<span><\/span>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"timeline-content medium-margin-top\">\r\n\t\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t\t<div class=\"timeline-point\"><i class=\"fa fa-circle-o\"><\/i><\/div>\r\n\t\t\t\t\t\t<div class=\"timeline-custom-col content-col \">\r\n\t\t\t\t\t\t\t<div class=\"timeline-location-block\">\r\n\t\t\t\t\t\t\t\t<p class=\"location-name\">\r\n\t\t\t\t\t\t\t\t\tValladolid\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-map-marker icon-marker\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t\t<div class=\"description\">\r\n\t\t\t\t\t\t\t\t\tEl primer destino ser\u00e1 Valladolid, en donde podr\u00e1s conocer un Pueblo M\u00e1gico con una arquitectura colonial que te sorprender\u00e1. \nDespu\u00e9s te llevaremos a una aldea maya para que conozcas todo acerca de ellos. \t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"timeline-custom-col image-col\" data-slick=\"{&quot;slidesToShow&quot;:1,&quot;slidesToScroll&quot;:1,&quot;dots&quot;:true,&quot;arrows&quot;:true,&quot;autoplay&quot;:true,&quot;infinite&quot;:true,&quot;speed&quot;:300,&quot;fade&quot;:false}\"><div class=\"timeline-image-block items\"><img decoding=\"async\" src=\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/valladolid-mayan-ruins-tour-chichen-itza.jpg\" alt=\"\"><\/div><\/div>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"timeline-block timeline-3\">\r\n\t\t\t\t<div class=\"timeline-title\">\r\n\t\t\t\t\t<span>2:00 pm<\/span>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"timeline-content medium-margin-top\">\r\n\t\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t\t<div class=\"timeline-point\"><i class=\"fa fa-circle-o\"><\/i><\/div>\r\n\t\t\t\t\t\t<div class=\"timeline-custom-col content-col \">\r\n\t\t\t\t\t\t\t<div class=\"timeline-location-block\">\r\n\t\t\t\t\t\t\t\t<p class=\"location-name\">\r\n\t\t\t\t\t\t\t\t\tChichen Itz\u00e1\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-map-marker icon-marker\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t\t<div class=\"description\">\r\n\t\t\t\t\t\t\t\t\tAproximadamente a las 2:00 pm llegaremos a Chichen Itz\u00e1 en donde podr\u00e1s apreciar de d\u00eda junto con un gu\u00eda certificado de los misterios que hermosa ciudad llena de misterio tiene. \t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"timeline-custom-col image-col\" data-slick=\"{&quot;slidesToShow&quot;:1,&quot;slidesToScroll&quot;:1,&quot;dots&quot;:true,&quot;arrows&quot;:true,&quot;autoplay&quot;:true,&quot;infinite&quot;:true,&quot;speed&quot;:300,&quot;fade&quot;:false}\"><div class=\"timeline-image-block items\"><img decoding=\"async\" src=\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/chichen-itza-mayan-ruins.jpg\" alt=\"\"><\/div><\/div>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"timeline-block timeline-4\">\r\n\t\t\t\t<div class=\"timeline-title\">\r\n\t\t\t\t\t<span><\/span>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"timeline-content medium-margin-top\">\r\n\t\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t\t<div class=\"timeline-point\"><i class=\"fa fa-circle-o\"><\/i><\/div>\r\n\t\t\t\t\t\t<div class=\"timeline-custom-col content-col \">\r\n\t\t\t\t\t\t\t<div class=\"timeline-location-block\">\r\n\t\t\t\t\t\t\t\t<p class=\"location-name\">\r\n\t\t\t\t\t\t\t\t\tCenote\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-map-marker icon-marker\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t\t<div class=\"description\">\r\n\t\t\t\t\t\t\t\t\tTe llevaremos a refrescarte al Cenote X-Cajum, podr\u00e1s sumergirte en las aguas cristalinas de este Cenote, relajarte y descansar un poco ya que el paseo sigue. \t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"timeline-custom-col image-col\" data-slick=\"{&quot;slidesToShow&quot;:1,&quot;slidesToScroll&quot;:1,&quot;dots&quot;:true,&quot;arrows&quot;:true,&quot;autoplay&quot;:true,&quot;infinite&quot;:true,&quot;speed&quot;:300,&quot;fade&quot;:false}\"><div class=\"timeline-image-block items\"><img decoding=\"async\" src=\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/cenote-x-cajum-mayan-ruins.jpg\" alt=\"\"><\/div><\/div>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"timeline-block timeline-5\">\r\n\t\t\t\t<div class=\"timeline-title\">\r\n\t\t\t\t\t<span><\/span>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"timeline-content medium-margin-top\">\r\n\t\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t\t<div class=\"timeline-point\"><i class=\"fa fa-circle-o\"><\/i><\/div>\r\n\t\t\t\t\t\t<div class=\"timeline-custom-col content-col \">\r\n\t\t\t\t\t\t\t<div class=\"timeline-location-block\">\r\n\t\t\t\t\t\t\t\t<p class=\"location-name\">\r\n\t\t\t\t\t\t\t\t\tCena Buffet\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-map-marker icon-marker\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t\t<div class=\"description\">\r\n\t\t\t\t\t\t\t\t\tSabemos que nadar puede ser muy cansado, por est\u00e1 raz\u00f3n te deleitaremos con una cena buffet de autentica cocina yucateca. \u00a1Deleitate con el saz\u00f3n yucateco que la noche apenas comienza! \t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"timeline-custom-col image-col\" data-slick=\"{&quot;slidesToShow&quot;:1,&quot;slidesToScroll&quot;:1,&quot;dots&quot;:true,&quot;arrows&quot;:true,&quot;autoplay&quot;:true,&quot;infinite&quot;:true,&quot;speed&quot;:300,&quot;fade&quot;:false}\"><div class=\"timeline-image-block items\"><img decoding=\"async\" src=\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/comida-buffet-tour-mayan-ruins-chichen-itza.jpg\" alt=\"\"><\/div><\/div>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"timeline-block timeline-6\">\r\n\t\t\t\t<div class=\"timeline-title\">\r\n\t\t\t\t\t<span>6:45 p.m.<\/span>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"timeline-content medium-margin-top\">\r\n\t\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t\t<div class=\"timeline-point\"><i class=\"fa fa-circle-o\"><\/i><\/div>\r\n\t\t\t\t\t\t<div class=\"timeline-custom-col content-col \">\r\n\t\t\t\t\t\t\t<div class=\"timeline-location-block\">\r\n\t\t\t\t\t\t\t\t<p class=\"location-name\">\r\n\t\t\t\t\t\t\t\t\tShow de Noche Chichen Itz\u00e1\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-map-marker icon-marker\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t\t<div class=\"description\">\r\n\t\t\t\t\t\t\t\t\tAproximadamente a las 18:45 regresaremos a Chichen Itz\u00e1 para que puedas deleitarte con el Show de Noche en Chichen Itz\u00e1. \nAlrededor de\u00a0 las 21:00 estar\u00e1s de regreso en tu hotel para que disfrutes de un merecido descanso.\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"timeline-custom-col image-col\" data-slick=\"{&quot;slidesToShow&quot;:1,&quot;slidesToScroll&quot;:1,&quot;dots&quot;:true,&quot;arrows&quot;:true,&quot;autoplay&quot;:true,&quot;infinite&quot;:true,&quot;speed&quot;:300,&quot;fade&quot;:false}\"><div class=\"timeline-image-block items\"><img decoding=\"async\" src=\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/chichen-itza-show-de-noche.jpg\" alt=\"\"><\/div><\/div>\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\r\n<div class=\"slz-shortcode block-title-4023165656a581ad4b8093 \">\r\n<h3 class=\"slz-shortcode title-style-3\">Horario sujeto a cambios<\/h3><\/div>\r\n[\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][vc_column_text]<\/p>\n<p style=\"font-size: 30px;\">Explorar m\u00e1s tours<\/p>\n<p>[\/vc_column_text]<div class=\"woocommerce columns-4 \"><ul class=\"products columns-4\">\n<li class=\"tm-has-options product type-product post-1466 status-publish first instock product_cat-sin-categorizar has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/mayanruins.mx\/es\/tour\/chichen-itza\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"245\" src=\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/chichen-itza-tours.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/chichen-itza-tours.jpg 450w, https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/chichen-itza-tours-300x245.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">Chichen Itz\u00e1<\/h2>\n\t<span class=\"price\">Desde <span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span>79<\/bdi><\/span> USD<\/span>\n<\/a><a href=\"?add-to-cart=1466\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button \" data-product_id=\"1466\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Chichen Itz\u00e1&rdquo;\" rel=\"nofollow\">A\u00f1adir al carrito<\/a><\/li>\n<li class=\"tm-has-options product type-product post-1478 status-publish instock product_cat-sin-categorizar has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/mayanruins.mx\/es\/tour\/chichen-itza-privado\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"245\" src=\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/visita-chichen-itza-tours.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/visita-chichen-itza-tours.jpg 450w, https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/visita-chichen-itza-tours-300x245.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">Chichen Itz\u00e1 Privado<\/h2>\n\t<span class=\"price\">Desde <span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span>410<\/bdi><\/span> USD<\/span>\n<\/a><a href=\"?add-to-cart=1478\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button \" data-product_id=\"1478\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Chichen Itz\u00e1 Privado&rdquo;\" rel=\"nofollow\">A\u00f1adir al carrito<\/a><\/li>\n<li class=\"tm-has-options product type-product post-1473 status-publish instock product_cat-sin-categorizar has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/mayanruins.mx\/es\/tour\/coba\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"245\" src=\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/cobas-ruin-from-mayan-ruins.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/cobas-ruin-from-mayan-ruins.jpg 450w, https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/cobas-ruin-from-mayan-ruins-300x245.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">Cob\u00e1<\/h2>\n\t<span class=\"price\">Desde <span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span>79<\/bdi><\/span> USD<\/span>\n<\/a><a href=\"?add-to-cart=1473\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button \" data-product_id=\"1473\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Cob\u00e1&rdquo;\" rel=\"nofollow\">A\u00f1adir al carrito<\/a><\/li>\n<li class=\"tm-has-options product type-product post-1468 status-publish last instock product_cat-sin-categorizar has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/mayanruins.mx\/es\/tour\/equinoccio-en-chichen-itza\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"245\" src=\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/chichen-itza-tours-piramide.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/chichen-itza-tours-piramide.jpg 450w, https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/chichen-itza-tours-piramide-300x245.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">Equinoccio en Chichen Itz\u00e1<\/h2>\n\t<span class=\"price\">Desde <span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span>99<\/bdi><\/span> USD<\/span>\n<\/a><a href=\"?add-to-cart=1468\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button \" data-product_id=\"1468\" data-product_sku=\"\" aria-label=\"Add to cart: &ldquo;Equinoccio en Chichen Itz\u00e1&rdquo;\" rel=\"nofollow\">A\u00f1adir al carrito<\/a><\/li>\n<\/ul>\n<\/div>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text] \u00a1Descubre todo acerca de los mayas con el Tour Show de Noche en Chichen Itz\u00e1! Ser\u00e1 un d\u00eda en donde podr\u00e1s llenarte de energ\u00eda en la antigua Chichen Itz\u00e1, podr\u00e1s conocer una de las nuevas siete maravillas del mundo, el campo de Juego de pelota, una aldea maya, sumergirte en las aguas cristalinas [&hellip;]<\/p>\n","protected":false},"featured_media":1505,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[93],"product_tag":[],"class_list":{"0":"post-1467","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sin-categorizar","7":"tm-has-options","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Show de Noche en Chichen Itz\u00e1<\/title>\n<meta name=\"description\" content=\"\u00a1Descubre todo acerca de los mayas de d\u00eda y de noche con el Tour Show de Noche en Chichen Itz\u00e1! Te encantar\u00e1 vivir esta experiencia m\u00e1gica con tu familia...\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Show de Noche en Chichen Itz\u00e1\" \/>\n<meta property=\"og:description\" content=\"\u00a1Descubre todo acerca de los mayas de d\u00eda y de noche con el Tour Show de Noche en Chichen Itz\u00e1! Te encantar\u00e1 vivir esta experiencia m\u00e1gica con tu familia...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/\" \/>\n<meta property=\"og:site_name\" content=\"Mayan Ruins\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-03T00:23:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/chichen-itza-night-show-at-mayan-ruins.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"367\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/\",\"url\":\"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/\",\"name\":\"Show de Noche en Chichen Itz\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/mayanruins.mx\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/chichen-itza-night-show-at-mayan-ruins.jpg\",\"datePublished\":\"2017-08-30T16:24:41+00:00\",\"dateModified\":\"2024-07-03T00:23:00+00:00\",\"description\":\"\u00a1Descubre todo acerca de los mayas de d\u00eda y de noche con el Tour Show de Noche en Chichen Itz\u00e1! Te encantar\u00e1 vivir esta experiencia m\u00e1gica con tu familia...\",\"breadcrumb\":{\"@id\":\"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/#primaryimage\",\"url\":\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/chichen-itza-night-show-at-mayan-ruins.jpg\",\"contentUrl\":\"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/chichen-itza-night-show-at-mayan-ruins.jpg\",\"width\":\"450\",\"height\":\"367\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mayanruins.mx\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\/\/mayanruins.mx\/es\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Show de Noche en Chichen Itz\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mayanruins.mx\/es\/#website\",\"url\":\"https:\/\/mayanruins.mx\/es\/\",\"name\":\"Mayan Ruins\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mayanruins.mx\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Show de Noche en Chichen Itz\u00e1","description":"\u00a1Descubre todo acerca de los mayas de d\u00eda y de noche con el Tour Show de Noche en Chichen Itz\u00e1! Te encantar\u00e1 vivir esta experiencia m\u00e1gica con tu familia...","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_MX","og_type":"article","og_title":"Show de Noche en Chichen Itz\u00e1","og_description":"\u00a1Descubre todo acerca de los mayas de d\u00eda y de noche con el Tour Show de Noche en Chichen Itz\u00e1! Te encantar\u00e1 vivir esta experiencia m\u00e1gica con tu familia...","og_url":"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/","og_site_name":"Mayan Ruins","article_modified_time":"2024-07-03T00:23:00+00:00","og_image":[{"width":450,"height":367,"url":"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/chichen-itza-night-show-at-mayan-ruins.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/","url":"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/","name":"Show de Noche en Chichen Itz\u00e1","isPartOf":{"@id":"https:\/\/mayanruins.mx\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/#primaryimage"},"image":{"@id":"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/#primaryimage"},"thumbnailUrl":"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/chichen-itza-night-show-at-mayan-ruins.jpg","datePublished":"2017-08-30T16:24:41+00:00","dateModified":"2024-07-03T00:23:00+00:00","description":"\u00a1Descubre todo acerca de los mayas de d\u00eda y de noche con el Tour Show de Noche en Chichen Itz\u00e1! Te encantar\u00e1 vivir esta experiencia m\u00e1gica con tu familia...","breadcrumb":{"@id":"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/#primaryimage","url":"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/chichen-itza-night-show-at-mayan-ruins.jpg","contentUrl":"https:\/\/mayanruins.mx\/es\/wp-content\/uploads\/sites\/2\/2017\/08\/chichen-itza-night-show-at-mayan-ruins.jpg","width":"450","height":"367"},{"@type":"BreadcrumbList","@id":"https:\/\/mayanruins.mx\/es\/tour\/show-de-noche-en-chichen-itza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mayanruins.mx\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/mayanruins.mx\/es\/shop\/"},{"@type":"ListItem","position":3,"name":"Show de Noche en Chichen Itz\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/mayanruins.mx\/es\/#website","url":"https:\/\/mayanruins.mx\/es\/","name":"Mayan Ruins","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mayanruins.mx\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/mayanruins.mx\/es\/wp-json\/wp\/v2\/product\/1467"}],"collection":[{"href":"https:\/\/mayanruins.mx\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mayanruins.mx\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mayanruins.mx\/es\/wp-json\/wp\/v2\/comments?post=1467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mayanruins.mx\/es\/wp-json\/wp\/v2\/media\/1505"}],"wp:attachment":[{"href":"https:\/\/mayanruins.mx\/es\/wp-json\/wp\/v2\/media?parent=1467"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mayanruins.mx\/es\/wp-json\/wp\/v2\/product_cat?post=1467"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mayanruins.mx\/es\/wp-json\/wp\/v2\/product_tag?post=1467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}